{"id":941,"date":"2023-06-28T10:02:16","date_gmt":"2023-06-28T13:02:16","guid":{"rendered":"https:\/\/www.mtexpo.com.br\/es\/?p=941"},"modified":"2023-06-28T10:06:24","modified_gmt":"2023-06-28T13:06:24","slug":"en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria","status":"publish","type":"post","link":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/","title":{"rendered":"<strong>En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda<\/strong>"},"content":{"rendered":"\n<p><em>La igualdad de g\u00e9nero a\u00fan es una realidad distante, pero la participaci\u00f3n de las mujeres ha aumentado entre los que obtienen el diploma<\/em><\/p>\n\n\n\n<p>\u00bfSab\u00eda que, de acuerdo con un Informe Cient\u00edfico de UNESCO publicado en febrero de 2022, solo el 33% de los investigadores cient\u00edficos en el mundo son mujeres? Pero, en el caso del Per\u00fa, ellas representan el 47,5% de los graduados en ingenier\u00eda en todo el pa\u00eds, n\u00famero que se aproxima a la mitad de todos los graduados, seg\u00fan el informe.<\/p>\n\n\n\n<p>Aunque la igualdad de g\u00e9nero a\u00fan tenga un largo camino por recorrer en diferentes sectores de la sociedad peruana, se destaca que la participaci\u00f3n de las mujeres ha demostrado ser significativa en el \u00e1rea cient\u00edfica. En el campo de los estudios, la tasa l\u00edquida de registros femeninos en la ense\u00f1anza superior tiene un porcentaje inferior: aument\u00f3 entre 2005-2016; pero, en 2016, de los 32,9% de alumnos inscritos en carreras vinculadas a Ciencia y Tecnolog\u00eda, solo el 29,2% corresponde a mujeres.<\/p>\n\n\n\n<p>Hay varios factores que empujan esta estad\u00edstica hacia abajo. Muchas veces, en raz\u00f3n de las ideas machistas, algunas instituciones piensan que, si contratan mujeres, ellas pedir\u00e1n licencia maternidad, autorizaciones u otras cosas que noten como negativas o que afecten de alguna forma el desempe\u00f1o en el trabajo.<\/p>\n\n\n\n<p>Bettit Salv\u00e1, ingeniera en industrias alimenticias y vicerrectora de la Universidad Le Cordon Bleu, destac\u00f3 en el Portal Business Empresarial que en Per\u00fa existen muchos prejuicios y piensan que la mujer solo debe dedicarse al cuidado de la casa, cuando este trabajo debe ser compartido.<\/p>\n\n\n\n<p>Sin embargo, seg\u00fan \u00e9l, muchas personas y entidades quieren promover la participaci\u00f3n de ni\u00f1as y mujeres en los campos de la ciencia, tecnolog\u00eda y la ingenier\u00eda. Hay empresas estimulando la participaci\u00f3n de ni\u00f1as en las escuelas para que se interesen m\u00e1s por esas carreras, estudien y tengan m\u00e1s representatividad.<\/p>\n\n\n\n<p>Las mujeres que compiten en proyectos tambi\u00e9n son premiadas, por ejemplo, si hay igualdad de g\u00e9nero en los equipos, reciben m\u00e1s puntos, y sucede lo mismo si el l\u00edder es una mujer La idea principal es aumentar la participaci\u00f3n femenina en el campo de la ciencia e innovaci\u00f3n.<\/p>\n\n\n\n<p>Bettit agrega a Business Empresarial que orient\u00f3 m\u00e1s de 30 pruebas de graduaci\u00f3n y posgrado, siendo que de sus alumnos de tesis el 90% son mujeres y solo el 10% son hombres. Muchas son madres que desean seguir estudiando y buscando participaci\u00f3n en el mercado.<\/p>\n\n\n\n<p>Por: Santelmo Camilo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La igualdad de g\u00e9nero a\u00fan es una realidad distante, pero la participaci\u00f3n de las mujeres ha aumentado entre los que obtienen el diploma<\/p>\n","protected":false},"author":7,"featured_media":942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda | M&amp;T Expo<\/title>\n<meta name=\"description\" content=\"La igualdad de g\u00e9nero a\u00fan es una realidad distante, pero la participaci\u00f3n de las mujeres ha aumentado entre los que obtienen el diploma\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda | M&amp;T Expo\" \/>\n<meta property=\"og:description\" content=\"La igualdad de g\u00e9nero a\u00fan es una realidad distante, pero la participaci\u00f3n de las mujeres ha aumentado entre los que obtienen el diploma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/\" \/>\n<meta property=\"og:site_name\" content=\"M&amp;T Expo - ES\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/feiramtexpo\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-28T13:02:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T13:06:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mtexpo.com.br\/es\/wp-content\/uploads\/sites\/3\/2023\/06\/MicrosoftTeams-image-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1149\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yasmin Ribeiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yasmin Ribeiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/\"},\"author\":{\"name\":\"Yasmin Ribeiro\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/person\/335d1f123b404f4eeee3c77d3eff4bfd\"},\"headline\":\"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda\",\"datePublished\":\"2023-06-28T13:02:16+00:00\",\"dateModified\":\"2023-06-28T13:06:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/\"},\"wordCount\":441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#organization\"},\"articleSection\":[\"Infraestructura\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/\",\"url\":\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/\",\"name\":\"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda | M&T Expo\",\"isPartOf\":{\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#website\"},\"datePublished\":\"2023-06-28T13:02:16+00:00\",\"dateModified\":\"2023-06-28T13:06:24+00:00\",\"description\":\"La igualdad de g\u00e9nero a\u00fan es una realidad distante, pero la participaci\u00f3n de las mujeres ha aumentado entre los que obtienen el diploma\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.mtexpo.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#website\",\"url\":\"https:\/\/www.mtexpo.com.br\/es\/\",\"name\":\"M&T Expo\",\"description\":\"Part of bauma NETWORK\",\"publisher\":{\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#organization\"},\"alternateName\":\"M&T Expo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mtexpo.com.br\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#organization\",\"name\":\"M&T Expo\",\"alternateName\":\"M&T Expo\",\"url\":\"https:\/\/www.mtexpo.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mtexpo.com.br\/es\/wp-content\/uploads\/sites\/3\/2022\/12\/logo-MT-expo.svg\",\"contentUrl\":\"https:\/\/www.mtexpo.com.br\/es\/wp-content\/uploads\/sites\/3\/2022\/12\/logo-MT-expo.svg\",\"width\":350,\"height\":70,\"caption\":\"M&T Expo\"},\"image\":{\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/feiramtexpo\/\",\"https:\/\/www.youtube.com\/c\/mtexpofeira\",\"https:\/\/www.instagram.com\/feiramtexpo\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/person\/335d1f123b404f4eeee3c77d3eff4bfd\",\"name\":\"Yasmin Ribeiro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bf734aef4167ed7e812cf407c1f725c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bf734aef4167ed7e812cf407c1f725c9?s=96&d=mm&r=g\",\"caption\":\"Yasmin Ribeiro\"},\"url\":\"https:\/\/www.mtexpo.com.br\/es\/author\/thiagobento\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda | M&T Expo","description":"La igualdad de g\u00e9nero a\u00fan es una realidad distante, pero la participaci\u00f3n de las mujeres ha aumentado entre los que obtienen el diploma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/","og_locale":"es_ES","og_type":"article","og_title":"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda | M&T Expo","og_description":"La igualdad de g\u00e9nero a\u00fan es una realidad distante, pero la participaci\u00f3n de las mujeres ha aumentado entre los que obtienen el diploma","og_url":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/","og_site_name":"M&amp;T Expo - ES","article_publisher":"https:\/\/www.facebook.com\/feiramtexpo\/","article_published_time":"2023-06-28T13:02:16+00:00","article_modified_time":"2023-06-28T13:06:24+00:00","og_image":[{"width":2560,"height":1149,"url":"https:\/\/www.mtexpo.com.br\/es\/wp-content\/uploads\/sites\/3\/2023\/06\/MicrosoftTeams-image-scaled.jpg","type":"image\/jpeg"}],"author":"Yasmin Ribeiro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Yasmin Ribeiro","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/#article","isPartOf":{"@id":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/"},"author":{"name":"Yasmin Ribeiro","@id":"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/person\/335d1f123b404f4eeee3c77d3eff4bfd"},"headline":"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda","datePublished":"2023-06-28T13:02:16+00:00","dateModified":"2023-06-28T13:06:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/"},"wordCount":441,"commentCount":0,"publisher":{"@id":"https:\/\/www.mtexpo.com.br\/es\/#organization"},"articleSection":["Infraestructura"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/","url":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/","name":"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda | M&T Expo","isPartOf":{"@id":"https:\/\/www.mtexpo.com.br\/es\/#website"},"datePublished":"2023-06-28T13:02:16+00:00","dateModified":"2023-06-28T13:06:24+00:00","description":"La igualdad de g\u00e9nero a\u00fan es una realidad distante, pero la participaci\u00f3n de las mujeres ha aumentado entre los que obtienen el diploma","breadcrumb":{"@id":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mtexpo.com.br\/es\/2023\/06\/28\/en-peru-las-mujeres-representan-el-475-de-graduados-en-ingenieria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mtexpo.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"En Per\u00fa, las mujeres representan el 47,5% de graduados en ingenier\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.mtexpo.com.br\/es\/#website","url":"https:\/\/www.mtexpo.com.br\/es\/","name":"M&T Expo","description":"Part of bauma NETWORK","publisher":{"@id":"https:\/\/www.mtexpo.com.br\/es\/#organization"},"alternateName":"M&T Expo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mtexpo.com.br\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.mtexpo.com.br\/es\/#organization","name":"M&T Expo","alternateName":"M&T Expo","url":"https:\/\/www.mtexpo.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.mtexpo.com.br\/es\/wp-content\/uploads\/sites\/3\/2022\/12\/logo-MT-expo.svg","contentUrl":"https:\/\/www.mtexpo.com.br\/es\/wp-content\/uploads\/sites\/3\/2022\/12\/logo-MT-expo.svg","width":350,"height":70,"caption":"M&T Expo"},"image":{"@id":"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/feiramtexpo\/","https:\/\/www.youtube.com\/c\/mtexpofeira","https:\/\/www.instagram.com\/feiramtexpo\/"]},{"@type":"Person","@id":"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/person\/335d1f123b404f4eeee3c77d3eff4bfd","name":"Yasmin Ribeiro","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.mtexpo.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bf734aef4167ed7e812cf407c1f725c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf734aef4167ed7e812cf407c1f725c9?s=96&d=mm&r=g","caption":"Yasmin Ribeiro"},"url":"https:\/\/www.mtexpo.com.br\/es\/author\/thiagobento\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/posts\/941"}],"collection":[{"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/comments?post=941"}],"version-history":[{"count":2,"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/posts\/941\/revisions"}],"predecessor-version":[{"id":944,"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/posts\/941\/revisions\/944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/media\/942"}],"wp:attachment":[{"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/media?parent=941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/categories?post=941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mtexpo.com.br\/es\/wp-json\/wp\/v2\/tags?post=941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}